{"id":2138,"date":"2025-03-25T14:48:17","date_gmt":"2025-03-25T10:18:17","guid":{"rendered":"https:\/\/abloolearasepahan.com\/?p=2138"},"modified":"2025-06-02T09:42:24","modified_gmt":"2025-06-02T06:12:24","slug":"%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1","status":"publish","type":"post","link":"https:\/\/abloolearasepahan.com\/ar\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/","title":{"rendered":"\u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u0645\u0639\u0631\u0641\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0646!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2138\" class=\"elementor elementor-2138\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf73a97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf73a97\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7636fa2\" data-id=\"7636fa2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c90418f elementor-widget elementor-widget-text-editor\" data-id=\"c90418f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0635\u0646\u0639\u062a \u062d\u06cc\u0627\u062a\u06cc\u060c \u0628\u0647 \u0637\u0648\u0631 \u0645\u062f\u0627\u0648\u0645 \u062f\u0631 \u062d\u0627\u0644 \u067e\u06cc\u0634\u0631\u0641\u062a \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647 \u0648\u0631\u06cc\u060c \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u0645\u062f\u0631\u0646 \u0645\u0627\u0646\u0646\u062f <strong>\u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong> \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0633\u0646\u062a\u06cc \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p><p>\u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631\u060c \u06a9\u0647 \u0634\u0627\u0645\u0644 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0622\u0628\u06cc\u0627\u0631\u06cc \u0642\u0637\u0631\u0647\u200c\u0627\u06cc \u0648 \u0628\u0627\u0631\u0627\u0646\u06cc \u0627\u0633\u062a\u060c \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0644\u0648\u0644\u0647\u200c\u0647\u0627 \u0648 \u067e\u0645\u067e\u200c\u0647\u0627\u060c \u0622\u0628 \u0631\u0627 \u0628\u0627 \u0641\u0634\u0627\u0631 \u0628\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u062f.<\/p><p>\u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 <a href=\"https:\/\/abloolearasepahan.com\/%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d9%84%d9%87-%d9%be%d9%84%db%8c-%d8%a7%d8%aa%db%8c%d9%84%d9%86-%d9%81%d8%b4%d8%a7%d8%b1-%d9%82%d9%88%db%8c\/\"><strong>\u062e\u0631\u06cc\u062f \u0644\u0648\u0644\u0647 \u067e\u0644\u06cc \u0627\u062a\u06cc\u0644\u0646 \u0641\u0634\u0627\u0631 \u0642\u0648\u06cc<\/strong><\/a> \u0648 \u0628\u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u0622\u0646 \u062f\u0631 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0632\u0645\u06cc\u0646 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0645\u0645\u06a9\u0646 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647\u00a0 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628\u060c \u06a9\u0627\u0647\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u060c \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0645\u0642\u062f\u0627\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc. \u0628\u0631\u0627\u06cc <strong>\u0627\u062c\u0631\u0627\u06cc \u0645\u0648\u0641\u0642\u06cc\u062a\u200c\u0622\u0645\u06cc\u0632 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong>\u060c \u0645\u062d\u0627\u0633\u0628\u0647 \u062f\u0642\u06cc\u0642 \u0641\u0634\u0627\u0631 \u06a9\u0627\u0631\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0639\u0648\u0627\u0645\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u0645\u0627\u0646\u0646\u062f \u0646\u0648\u0639 \u06af\u06cc\u0627\u0647\u060c \u0646\u0648\u0639 \u062e\u0627\u06a9\u060c \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc\u06cc \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f. \u0641\u0631\u0645\u0648\u0644\u200c\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0628\u0631\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0627\u06cc\u0646 \u0641\u0634\u0627\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f1c563 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f1c563\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ccf0cfb\" data-id=\"ccf0cfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a6edc1 elementor-widget elementor-widget-image\" data-id=\"0a6edc1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/how-to-perfurme-under-pressure-irragation-webp.webp\" class=\"attachment-large size-large wp-image-2147\" alt=\"\" srcset=\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/how-to-perfurme-under-pressure-irragation-webp.webp 1000w, https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/how-to-perfurme-under-pressure-irragation-webp-300x150.webp 300w, https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/how-to-perfurme-under-pressure-irragation-webp-768x384.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-049e17a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"049e17a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed6ca44\" data-id=\"ed6ca44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8007e63 elementor-widget elementor-widget-heading\" data-id=\"8007e63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0686\u06cc\u0633\u062a\u061f<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d23513a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d23513a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa032ff\" data-id=\"aa032ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cf867f elementor-widget elementor-widget-text-editor\" data-id=\"8cf867f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u062f\u0648 \u0631\u0648\u0634 \u0627\u0635\u0644\u06cc \u0628\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f: \u0622\u0628\u06cc\u0627\u0631\u06cc \u0633\u0646\u062a\u06cc (\u062b\u0642\u0644\u06cc) \u0648 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0645\u062f\u0631\u0646 (\u062a\u062d\u062a \u0641\u0634\u0627\u0631). \u0622\u0628\u06cc\u0627\u0631\u06cc \u0633\u0646\u062a\u06cc \u0631\u0648\u0634\u06cc \u0642\u062f\u06cc\u0645\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0622\u0628 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0646\u06cc\u0631\u0648\u06cc \u062c\u0627\u0630\u0628\u0647 \u0648 \u0627\u062e\u062a\u0644\u0627\u0641 \u0627\u0631\u062a\u0641\u0627\u0639 \u0627\u0632 \u0645\u0646\u0628\u0639 \u0622\u0628 \u0628\u0647 \u0632\u0645\u06cc\u0646 \u0645\u0646\u062a\u0642\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p><p><strong> \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong> \u0633\u06cc\u0633\u062a\u0645\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0622\u0628 \u0628\u0627 \u0641\u0634\u0627\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0641\u0634\u0627\u0631 \u0627\u062a\u0645\u0633\u0641\u0631 (\u0641\u0634\u0627\u0631 \u0647\u0648\u0627) \u062f\u0631 \u0644\u0648\u0644\u0647\u200c\u0647\u0627 \u0648 \u0627\u062a\u0635\u0627\u0644\u0627\u062a \u0632\u06cc\u0631\u0632\u0645\u06cc\u0646\u06cc \u062c\u0631\u06cc\u0627\u0646 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634\u060c \u067e\u0645\u067e \u0622\u0628 \u0631\u0627 \u0628\u0627 \u0641\u0634\u0627\u0631 \u0628\u0647 \u062d\u0631\u06a9\u062a \u062f\u0631\u0645\u06cc\u200c\u0622\u0648\u0631\u062f \u0648 \u0628\u0633\u062a\u0647 \u0628\u0647 \u0646\u0648\u0639 \u0633\u06cc\u0633\u062a\u0645 (\u0628\u0627\u0631\u0627\u0646\u06cc\u060c \u0642\u0637\u0631\u0647\u200c\u0627\u06cc \u0648 \u063a\u06cc\u0631\u0647) \u0628\u0647 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0632\u0645\u06cc\u0646 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c8075a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c8075a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6901b6\" data-id=\"a6901b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1caad1a elementor-widget elementor-widget-heading\" data-id=\"1caad1a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0646\u0648\u0627\u0639 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7eb389 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7eb389\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca8a2c6\" data-id=\"ca8a2c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ffe640 elementor-widget elementor-widget-text-editor\" data-id=\"1ffe640\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631\u060c \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631\u0627\u06cc \u0631\u0633\u0627\u0646\u062f\u0646 \u0622\u0628 \u0628\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u062f\u0648 \u062f\u0633\u062a\u0647 \u06a9\u0644\u06cc \u062a\u0642\u0633\u06cc\u0645 \u06a9\u0631\u062f: \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0627\u0631\u0627\u0646\u06cc \u06a9\u0647 \u0622\u0628 \u0631\u0627 \u0645\u0627\u0646\u0646\u062f \u0628\u0627\u0631\u0627\u0646 \u0628\u0631 \u0631\u0648\u06cc \u06af\u06cc\u0627\u0647\u0627\u0646 \u0645\u06cc\u200c\u067e\u0627\u0634\u062f \u0648 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0645\u0648\u0636\u0639\u06cc \u06a9\u0647 \u0622\u0628 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0633\u062a\u0642\u06cc\u0645 \u0648 \u062f\u0631 \u0646\u0632\u062f\u06cc\u06a9\u06cc \u0631\u06cc\u0634\u0647 \u06af\u06cc\u0627\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p><p>\u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u062f\u0633\u062a\u0647\u200c\u0647\u0627\u060c \u0627\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641\u06cc \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0628\u0633\u062a\u0647 \u0628\u0647 \u0646\u0648\u0639 \u06af\u06cc\u0627\u0647\u060c \u0634\u0631\u0627\u06cc\u0637 \u0632\u0645\u06cc\u0646 \u0648 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc\u060c \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d81aaca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d81aaca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b4e1fd\" data-id=\"2b4e1fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a080adc elementor-widget elementor-widget-heading\" data-id=\"a080adc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"> \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0627\u0631\u0627\u0646\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-875acbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"875acbc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8aaafb5\" data-id=\"8aaafb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80ae9ab elementor-widget elementor-widget-text-editor\" data-id=\"80ae9ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u062f\u0631 \u0631\u0648\u0634 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0627\u0631\u0627\u0646\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9\u060c \u0622\u0628\u067e\u0627\u0634\u200c\u0647\u0627 \u0631\u0648\u06cc \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0627\u0645 \u0628\u0627\u0644 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0627 \u0641\u0627\u0635\u0644\u0647\u200c\u0647\u0627\u06cc \u0645\u0634\u062e\u0635 \u0646\u0635\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u062c\u0627\u0628\u0647\u200c\u062c\u0627\u06cc\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0648\u0633\u0637 \u0646\u06cc\u0631\u0648\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0647 \u0635\u0648\u0631\u062a \u062b\u0627\u0628\u062a\u060c \u0645\u062a\u062d\u0631\u06a9\u060c \u0646\u06cc\u0645\u0647\u200c\u0645\u062a\u062d\u0631\u06a9 \u0648 \u062b\u0627\u0628\u062a \u0628\u0627 \u0622\u0628\u067e\u0627\u0634 \u0645\u062a\u062d\u0631\u06a9 \u0627\u062c\u0631\u0627 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p><p>\u062f\u0631 \u0627\u06cc\u0631\u0627\u0646\u060c \u0631\u0648\u0634 \u0622\u0628\u06cc\u0627\u0631\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u062b\u0627\u0628\u062a \u0628\u0627 \u0622\u0628\u067e\u0627\u0634\u200c\u0647\u0627\u06cc \u0645\u062a\u062d\u0631\u06a9\u060c \u0628\u0647 \u0648\u06cc\u0698\u0647 \u062f\u0631 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0628\u0627\u062f\u062e\u06cc\u0632\u060c \u06a9\u0627\u0631\u0628\u0631\u062f \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634\u060c \u067e\u0645\u067e \u0622\u0628\u060c <a href=\"https:\/\/abloolearasepahan.com\/%d9%84%d9%88%d9%84%d9%87-%d9%be%d9%84%db%8c-%d8%a7%d8%aa%db%8c%d9%84%d9%86-%d8%a2%d8%a8%d8%b1%d8%b3%d8%a7%d9%86%db%8c\/\"><strong>\u0644\u0648\u0644\u0647 \u067e\u0644\u06cc \u0627\u062a\u06cc\u0644\u0646 \u0622\u0628<\/strong><\/a> \u0627\u0635\u0644\u06cc \u0648 \u0641\u0631\u0639\u06cc \u0648 \u0628\u0627\u0644\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062f\u0631 \u0637\u0648\u0644 \u0641\u0635\u0644 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062b\u0627\u0628\u062a \u0645\u06cc\u200c\u0645\u0627\u0646\u0646\u062f \u0648 \u0641\u0642\u0637 \u0622\u0628\u067e\u0627\u0634\u200c\u0647\u0627 \u06a9\u0647 \u0631\u0648\u06cc \u0634\u06cc\u0631\u0647\u0627\u06cc \u062e\u0648\u062f\u06a9\u0627\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u0646\u062f\u060c \u0631\u0648\u06cc \u0628\u0627\u0644\u200c\u0647\u0627 \u062c\u0627\u0628\u0647\u200c\u062c\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p><p>\u062f\u0631 \u0631\u0648\u0634 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0627\u0631\u0627\u0646\u06cc \u0645\u06a9\u0627\u0646\u06cc\u0632\u0647\u060c \u0628\u0631\u0627\u06cc \u062c\u0627\u0628\u0647\u200c\u062c\u0627\u06cc\u06cc \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0622\u0628 \u0627\u0632 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u06a9\u0627\u0646\u06cc\u06a9\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p><p>\u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0628\u0627\u0644\u0627\u06cc \u0646\u0635\u0628 \u0648 \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc\u060c \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0628\u0632\u0631\u06af \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0627\u0631\u0627\u0646\u06cc \u0645\u06a9\u0627\u0646\u06cc\u0632\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0648\u06cc\u0644\u0645\u0648\u0648\u060c \u06af\u0627\u0646\u060c \u0633\u0646\u062a\u0631\u067e\u06cc\u0648\u0648\u062a \u0648 \u0644\u06cc\u0646\u06cc\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe83c65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe83c65\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-598ed56\" data-id=\"598ed56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05ea5e9 elementor-widget elementor-widget-heading\" data-id=\"05ea5e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0622\u0628\u06cc\u0627\u0631\u06cc \u0646\u0642\u0637\u0647 \u0627\u06cc<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e38d3ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e38d3ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46c1574\" data-id=\"46c1574\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e9fe5b elementor-widget elementor-widget-text-editor\" data-id=\"4e9fe5b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 <strong>\u0627\u0646\u0648\u0627\u0639 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong> \u0622\u0628\u06cc\u0627\u0631\u06cc \u0646\u0642\u0637\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0622\u0628 \u0628\u0627 \u0641\u0634\u0627\u0631 \u06a9\u0645 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0644\u0648\u0644\u0647 \u0647\u0627\u06cc \u0628\u0627\u0631\u06cc\u06a9 \u0628\u0647 \u0635\u0648\u0631\u062a \u0642\u0637\u0631\u0647 \u06cc\u0627 \u062c\u0631\u06cc\u0627\u0646 \u0645\u0644\u0627\u06cc\u0645 \u0628\u0647 \u067e\u0627\u06cc \u06af\u06cc\u0627\u0647 \u0645\u06cc \u0631\u0633\u062f.<\/p><p>\u0627\u06cc\u0646 \u0631\u0648\u0634 \u0627\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641\u06cc \u062f\u0627\u0631\u062f\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0646\u0648\u0627\u0631\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0632\u0645\u06cc\u0646 \u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0645\u0646\u0627\u0633\u0628 \u062a\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634\u060c \u0646\u0648\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0642\u0637\u0631\u0647 \u0686\u06a9\u0627\u0646 \u0647\u0627 \u0628\u0647 \u0641\u0627\u0635\u0644\u0647 \u0647\u0627\u06cc \u0645\u0639\u06cc\u0646 \u0631\u0648\u06cc \u0622\u0646\u0647\u0627 \u0646\u0635\u0628 \u0634\u062f\u0647 \u0627\u0646\u062f\u060c \u062f\u0631 \u0631\u062f\u06cc\u0641 \u0647\u0627\u06cc \u06a9\u0634\u062a \u0648 \u0646\u0632\u062f\u06cc\u06a9 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ebf9863 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebf9863\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac27861\" data-id=\"ac27861\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6e66d7 elementor-widget elementor-widget-heading\" data-id=\"f6e66d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0622\u0628\u06cc\u0627\u0631\u06cc \u0642\u0637\u0631\u0647\u200c\u0627\u06cc \u0632\u06cc\u0631\u0632\u0645\u06cc\u0646\u06cc<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1768eb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1768eb8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81fd36c\" data-id=\"81fd36c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa3ae39 elementor-widget elementor-widget-text-editor\" data-id=\"fa3ae39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634\u060c \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0622\u0628 \u0648 \u0642\u0637\u0631\u0647\u200c\u0686\u06a9\u0627\u0646\u200c\u0647\u0627 \u0632\u06cc\u0631 \u062e\u0627\u06a9 \u0648 \u0646\u0632\u062f\u06cc\u06a9 \u0631\u06cc\u0634\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f.<\/p><p>\u0622\u0628 \u0628\u0647 \u0622\u0631\u0627\u0645\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627 \u062e\u0627\u0631\u062c \u0634\u062f\u0647 \u0648 \u062e\u0627\u06a9 \u0627\u0637\u0631\u0627\u0641 \u0631\u06cc\u0634\u0647 \u0631\u0627 \u0645\u0631\u0637\u0648\u0628 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0647 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628 \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0632 \u062a\u0628\u062e\u06cc\u0631 \u0633\u0637\u062d\u06cc \u0622\u0628 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61e663c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61e663c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74af133\" data-id=\"74af133\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d9b948 elementor-widget elementor-widget-image\" data-id=\"5d9b948\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/irrigation-under-pressure-types-webp.webp\" class=\"attachment-large size-large wp-image-2151\" alt=\"\" srcset=\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/irrigation-under-pressure-types-webp.webp 1000w, https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/irrigation-under-pressure-types-webp-300x150.webp 300w, https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/irrigation-under-pressure-types-webp-768x384.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c078851 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c078851\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85777d7\" data-id=\"85777d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35b7712 elementor-widget elementor-widget-heading\" data-id=\"35b7712\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f332d61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f332d61\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df032c3\" data-id=\"df032c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1c55f5 elementor-widget elementor-widget-text-editor\" data-id=\"b1c55f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0642\u0628\u0644\u0627\u064b \u0630\u06a9\u0631 \u0634\u062f\u060c \u0631\u0648\u0634 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0648 \u0628\u0627\u0632\u062f\u0647\u06cc \u0628\u0627\u0644\u0627 \u062f\u0631 \u0635\u0646\u0639\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u0627\u0645\u0631\u0648\u0632\u0647 \u0628\u0627 \u0627\u0633\u062a\u0642\u0628\u0627\u0644 \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u06cc \u0645\u0648\u0627\u062c\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0646\u0648\u06cc\u0646 \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0633\u0646\u062a\u06cc \u0648 \u0642\u062f\u06cc\u0645\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc\u060c \u0645\u0632\u0627\u06cc\u0627\u06cc \u0645\u062a\u0639\u062f\u062f\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0622\u0646\u200c\u0647\u0627 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p><p>\u06a9\u0627\u0647\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0646\u06cc\u0631\u0648\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc: \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0627\u067e\u0631\u0627\u062a\u0648\u0631\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f \u0648 \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647\u060c \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0646\u06cc\u0632 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e87e48c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e87e48c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8889f9a\" data-id=\"8889f9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d2a42c elementor-widget elementor-widget-text-editor\" data-id=\"0d2a42c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u0622\u0628\u06cc\u0627\u0631\u06cc \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u0648 \u0631\u0634\u062f \u0647\u0645\u0633\u0627\u0646: \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627 \u0622\u0628 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u0632\u0645\u06cc\u0646 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u062a\u0648\u0632\u06cc\u0639 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u06a9\u0647 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0631\u0634\u062f \u0647\u0645\u0633\u0627\u0646 \u0648 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<\/li><li>\u0622\u0628\u06cc\u0627\u0631\u06cc \u0645\u0646\u0627\u0637\u0642 \u0646\u0627\u0647\u0645\u0648\u0627\u0631: \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0627\u0645\u06a9\u0627\u0646 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0645\u0646\u0638\u0645 \u0648 \u0645\u0646\u0627\u0633\u0628 \u0631\u0627 \u062f\u0631 \u0645\u0646\u0627\u0637\u0642\u06cc \u0628\u0627 \u0634\u06cc\u0628 \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u06a9\u0647 \u062f\u0631 \u0631\u0648\u0634 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062b\u0642\u0644\u06cc \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0627\u0645\u06a9\u0627\u0646\u200c\u067e\u0630\u06cc\u0631 \u0646\u06cc\u0633\u062a.<\/li><li>\u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u0635\u0631\u0641 \u0622\u0628: \u06a9\u0646\u062a\u0631\u0644 \u062f\u0642\u06cc\u0642 \u0645\u06cc\u0632\u0627\u0646 \u0622\u0628\u200c\u0631\u0633\u0627\u0646\u06cc \u062a\u0648\u0633\u0637 \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u060c \u0645\u0646\u062c\u0631 \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0645\u0635\u0631\u0641 \u0622\u0628 \u0648 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0647\u062f\u0631 \u0631\u0641\u062a \u0645\u0646\u0627\u0628\u0639 \u0622\u0628\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f.<\/li><li>\u06a9\u0648\u062f\u062f\u0647\u06cc \u06a9\u0646\u062a\u0631\u0644\u200c\u0634\u062f\u0647: \u0627\u0645\u06a9\u0627\u0646 \u06a9\u0648\u062f\u062f\u0647\u06cc \u06a9\u0627\u0645\u0644\u0627\u064b \u06a9\u0646\u062a\u0631\u0644\u200c\u0634\u062f\u0647 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631\u060c \u0628\u0647 \u06a9\u0634\u0627\u0648\u0631\u0632\u0627\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0645\u0648\u0627\u062f \u0645\u063a\u0630\u06cc \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u062f\u0642\u06cc\u0642 \u0628\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0628\u0631\u0633\u0627\u0646\u0646\u062f.<\/li><li>\u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0631\u0639\u062a \u0622\u0628\u06cc\u0627\u0631\u06cc: \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631\u060c \u0633\u0631\u0639\u062a \u0622\u0628\u06cc\u0627\u0631\u06cc \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0648 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f177e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f177e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7db686\" data-id=\"b7db686\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e5c845 elementor-widget elementor-widget-text-editor\" data-id=\"8e5c845\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #3366ff;\">\u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0645\u0639\u0627\u06cc\u0628\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0634\u0648\u0646\u062f. \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0646\u0628\u0639 \u0628\u0631\u0642 \u0648 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0648\u0644\u06cc\u0647 \u0628\u0627\u0644\u0627 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0648 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0627\u06cc\u0628 \u0647\u0633\u062a\u0646\u062f.<\/span><\/p><p><span style=\"color: #3366ff;\">\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0636\u0627\u0641\u06cc \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639\u060c \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0628\u0644\u0646\u062f\u0645\u062f\u062a \u0645\u0642\u0631\u0648\u0646\u200c\u0628\u0647\u200c\u0635\u0631\u0641\u0647 \u0628\u0627\u0634\u062f\u060c \u0627\u0645\u0627 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0631\u06cc\u0632\u06cc \u062f\u0642\u06cc\u0642 \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u062f\u0627\u0631\u062f. \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0627\u06cc\u062f \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u060c \u0628\u0648\u062f\u062c\u0647 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u062e\u0627\u0635 \u0647\u0631 \u067e\u0631\u0648\u0698\u0647 \u0635\u0648\u0631\u062a \u06af\u06cc\u0631\u062f.<\/span><\/p><p><span style=\"color: #3366ff;\">\u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062f\u0631 \u0646\u0638\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0627\u0646\u0631\u0698\u06cc \u062a\u062c\u062f\u06cc\u062f\u067e\u0630\u06cc\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0627 \u062d\u062f\u0648\u062f\u06cc \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0646\u0627\u0628\u0639 \u0628\u0631\u0642 \u062e\u0627\u0631\u062c\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u062f \u0648 \u0628\u0647 \u067e\u0627\u06cc\u062f\u0627\u0631\u06cc \u0627\u06cc\u0646 \u0631\u0648\u0634 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-869880f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"869880f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b895776\" data-id=\"b895776\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd2705d elementor-widget elementor-widget-heading\" data-id=\"dd2705d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0622\u0645\u0648\u0632\u0634 \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a365184 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a365184\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0626eef\" data-id=\"0626eef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8174103 elementor-widget elementor-widget-text-editor\" data-id=\"8174103\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0628\u0631\u0627\u06cc<strong> \u0622\u0645\u0648\u0632\u0634 \u0646\u062d\u0648\u0647 \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong>\u060c \u0628\u0627\u06cc\u062f \u0628\u0647 \u0639\u0648\u0627\u0645\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u062a\u0648\u062c\u0647 \u06a9\u0631\u062f.<\/p><p>\u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0634\u0627\u0645\u0644 \u0634\u0631\u0627\u06cc\u0637 \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc\u06cc \u0645\u0646\u0637\u0642\u0647 \u0645\u0627\u0646\u0646\u062f \u062f\u0645\u0627 \u0648 \u0645\u06cc\u0632\u0627\u0646 \u0628\u0627\u062f\u060c \u067e\u0633\u062a\u06cc \u0648 \u0628\u0644\u0646\u062f\u06cc \u0632\u0645\u06cc\u0646\u060c \u0646\u0648\u0639 \u0648 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u06a9\u060c \u0646\u0648\u0639 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u0645\u06cc\u0632\u0627\u0646 \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0622\u0628 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0628\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc\u060c \u0634\u0631\u0627\u06cc\u0637 \u062a\u0627\u0645\u06cc\u0646 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0639\u062f\u0627\u062f \u0646\u06cc\u0631\u0648\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc \u0644\u0627\u0632\u0645\u060c \u0645\u06cc\u0632\u0627\u0646 \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0646\u0627\u0628\u0639 \u0622\u0628\u06cc\u060c \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u060c \u0646\u062d\u0648\u0647 \u0628\u0647\u0631\u0647\u200c\u0628\u0631\u062f\u0627\u0631\u06cc \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0633\u06cc\u0633\u062a\u0645\u060c \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0641\u0631\u0647\u0646\u06af\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc <strong>\u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong> \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0627\u062c\u0631\u0627\u06cc \u0645\u0648\u0641\u0642 \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645\u060c \u0628\u0627\u06cc\u062f \u062a\u0627\u062b\u06cc\u0631 \u0647\u0631 \u06cc\u06a9 \u0627\u0632 \u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0628\u0647 \u062f\u0642\u062a \u0628\u0631\u0631\u0633\u06cc \u0634\u0648\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a841aa9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a841aa9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1b503f\" data-id=\"d1b503f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1270615 elementor-widget elementor-widget-heading\" data-id=\"1270615\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0628\u0631\u0627\u06cc \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4378aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4378aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4661c1c\" data-id=\"4661c1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15d0f85 elementor-widget elementor-widget-text-editor\" data-id=\"15d0f85\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0628\u0631\u0627\u06cc \u0627\u062c\u0631\u0627\u06cc \u0633\u06cc\u0633\u062a\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631\u060c \u0627\u0628\u062a\u062f\u0627 \u0628\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0627\u0648\u0644\u06cc\u0647\u200c\u0627\u06cc \u0646\u06cc\u0627\u0632 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0622\u0646 \u0637\u0631\u0627\u062d\u06cc \u0627\u0648\u0644\u06cc\u0647 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0633\u067e\u0633 \u0628\u0627 \u062c\u0645\u0639\u200c\u0622\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0642\u06cc\u0642\u200c\u062a\u0631\u060c \u0633\u06cc\u0633\u062a\u0645 \u0627\u0635\u0644\u0627\u062d \u0645\u06cc\u200c\u06af\u0631\u062f\u062f.<\/p><p>\u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0627\u06cc\u0646 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0634\u0627\u0645\u0644 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0627\u0633\u062a: \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc\u060c \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0648 \u062e\u0627\u06a9\u060c \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0646\u06cc\u0627\u0632 \u0622\u0628\u06cc \u0648 \u0638\u0631\u0641\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645\u060c \u0627\u0628\u0639\u0627\u062f\u060c \u0634\u06a9\u0644 \u0648 \u0622\u0631\u0627\u06cc\u0634 \u0645\u0632\u0627\u0631\u0639\u060c \u0645\u06cc\u0632\u0627\u0646 \u0644\u0648\u0644\u0647 \u0622\u0628 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632\u060c \u0646\u0648\u0639 \u0632\u0631\u0627\u0639\u062a \u062f\u0631 \u0627\u0631\u0627\u0636\u06cc \u0645\u062c\u0627\u0648\u0631 \u0648 \u0645\u0648\u0627\u0646\u0639 \u0645\u0648\u062c\u0648\u062f (\u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u0648\u0627\u0631\u0647\u0627\u060c \u062f\u0631\u062e\u062a\u200c\u0647\u0627\u060c \u06a9\u0627\u0628\u0644 \u0628\u0631\u0642\u060c \u062c\u0627\u062f\u0647 \u0648 \u063a\u06cc\u0631\u0647)\u060c \u0648\u0636\u0639\u06cc\u062a \u0645\u0631\u0632\u0647\u0627\u06cc \u0632\u0645\u06cc\u0646 \u0648 \u0645\u0627\u0644\u06a9\u06cc\u062a \u0622\u0646\u060c \u0645\u0627\u0644\u06a9\u06cc\u062a \u0627\u0631\u0627\u0636\u06cc \u0627\u0637\u0631\u0627\u0641\u060c \u0645\u062d\u0644 \u0686\u0627\u0647 \u0622\u0628 \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 \u0646\u0642\u0627\u0637 \u0645\u062e\u062a\u0644\u0641 \u0632\u0645\u06cc\u0646\u060c \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u06a9\u0645\u06cc\u062a \u0622\u0628 \u062f\u0631 \u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0633\u0627\u0644\u060c \u0634\u0631\u0627\u06cc\u0637 \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc\u06cc\u060c \u0648 \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0648 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062e\u0627\u06a9\u060c \u0636\u0631\u0648\u0631\u06cc \u0647\u0633\u062a\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd028bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd028bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-290ee3a\" data-id=\"290ee3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92feafe elementor-widget elementor-widget-text-editor\" data-id=\"92feafe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<blockquote><p>\u0628\u0631\u0627\u06cc \u0627\u0637\u0644\u0627\u0639 \u0627\u0632 <a href=\"https:\/\/abloolearasepahan.com\/%d9%86%d8%b5%d8%a8-%d9%84%d9%88%d9%84%d9%87-%d9%be%d9%84%db%8c-%d8%a7%d8%aa%db%8c%d9%84%d9%86-%d9%81%d8%b4%d8%a7%d8%b1-%d9%82%d9%88%db%8c\/\"><strong>\u0645\u0631\u0627\u062d\u0644 \u0646\u0635\u0628 \u0644\u0648\u0644\u0647 \u067e\u0644\u06cc \u0627\u062a\u06cc\u0644\u0646 \u0641\u0634\u0627\u0631 \u0642\u0648\u06cc<\/strong><\/a> \u0628\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0628\u0647 \u0645\u0637\u0627\u0644\u0628 \u0633\u0627\u06cc\u062a \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f!<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf9b18f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf9b18f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d989d80\" data-id=\"d989d80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ff8197 elementor-widget elementor-widget-heading\" data-id=\"1ff8197\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0648\u0634 \u0645\u0646\u0627\u0633\u0628 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41c053f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41c053f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20b8e2f\" data-id=\"20b8e2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d9031f elementor-widget elementor-widget-text-editor\" data-id=\"4d9031f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u06cc\u0648\u0647\u0654 \u0628\u0647\u06cc\u0646\u0647\u0654 \u0622\u0628\u06cc\u0627\u0631\u06cc\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0631\u06a9\u0627\u0646 \u06a9\u0644\u06cc\u062f\u06cc \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0627\u062c\u0631\u0627\u06cc \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u062a\u0639\u06cc\u06cc\u0646 \u0631\u0648\u0634 \u0645\u0646\u0627\u0633\u0628\u060c \u0639\u0648\u0627\u0645\u0644 \u06af\u0648\u0646\u0627\u06af\u0648\u0646\u06cc \u062f\u062e\u06cc\u0644 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0622\u0646\u200c\u0647\u0627 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9099e17 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9099e17\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8aa476a\" data-id=\"8aa476a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-707e67a elementor-widget elementor-widget-text-editor\" data-id=\"707e67a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u0634\u0631\u0627\u06cc\u0637 \u062c\u0648\u06cc \u0648 \u0622\u0628\u200c\u0648\u0647\u0648\u0627\u06cc\u06cc \u0645\u0646\u0637\u0642\u0647<\/li><li>\u062a\u0648\u067e\u0648\u06af\u0631\u0627\u0641\u06cc \u0632\u0645\u06cc\u0646 \u0648 \u0645\u0646\u0627\u0628\u0639 \u0627\u0646\u0631\u0698\u06cc \u0645\u0648\u062c\u0648\u062f<\/li><li>\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0622\u0628 \u0648 \u062e\u0627\u06a9<\/li><li>\u0646\u0648\u0639 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc<\/li><li>\u0645\u0633\u0627\u0626\u0644 \u0641\u0631\u0647\u0646\u06af\u06cc \u0648 \u0646\u06cc\u0631\u0648\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc \u0645\u0648\u062c\u0648\u062f<\/li><li>\u0646\u062d\u0648\u0647\u0654 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0648 \u0628\u0647\u0631\u0647\u200c\u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc<\/li><li>\u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0648 \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd3a3e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd3a3e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f4079c\" data-id=\"4f4079c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9091e4 elementor-widget elementor-widget-text-editor\" data-id=\"e9091e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0647\u0631\u06cc\u06a9 \u0627\u0632 \u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a\u200c\u0647\u0627 \u0628\u0627\u0634\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06fcc8a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06fcc8a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85df1e7\" data-id=\"85df1e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0308990 elementor-widget elementor-widget-text-editor\" data-id=\"0308990\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627 \u0628\u0647\u200c\u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u062a\u0646\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0627\u0645\u06a9\u0627\u0646\u200c\u067e\u0630\u06cc\u0631 \u0628\u0627\u0634\u062f \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0646\u0638\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0639\u0645\u0644\u06cc \u062a\u0648\u062c\u06cc\u0647 \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/li><li>\u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u06af\u0648\u0646\u0627\u06af\u0648\u0646 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0627\u0644\u062a\u060c \u0631\u0648\u0634\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0627\u0632 \u0646\u0638\u0631 \u0641\u0646\u06cc \u0648 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0647\u200c\u0635\u0631\u0641\u0647\u200c\u062a\u0631 \u0628\u0627\u0634\u062f\u060c \u0686\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0633\u0646\u062a\u06cc \u0648 \u0686\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631.<\/li><li>\u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627\u064b \u0628\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0645\u0631\u0628\u0648\u0637 \u0646\u06cc\u0633\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 <strong>\u0633\u06cc\u0633\u062a\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong> \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u0647\u062f\u0627\u0641 \u062e\u0627\u0635 \u0636\u0631\u0648\u0631\u06cc \u0645\u06cc\u200c\u0633\u0627\u0632\u0646\u062f (\u0645\u0627\u0646\u0646\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0628\u0627\u0631\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u06cc\u062e\u200c\u0632\u062f\u06af\u06cc).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1981329 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1981329\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51e0c24\" data-id=\"51e0c24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e19f992 elementor-widget elementor-widget-image\" data-id=\"e19f992\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/under-pressure-irrigation-equipments.jpg\" class=\"attachment-large size-large wp-image-2153\" alt=\"\" srcset=\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/under-pressure-irrigation-equipments.jpg 1000w, https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/under-pressure-irrigation-equipments-300x150.jpg 300w, https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/under-pressure-irrigation-equipments-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccbe2b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccbe2b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c8973c\" data-id=\"5c8973c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45bb2f8 elementor-widget elementor-widget-heading\" data-id=\"45bb2f8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0646\u0642\u0634\u0647\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8f2bf6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8f2bf6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-119e014\" data-id=\"119e014\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77d46de elementor-widget elementor-widget-text-editor\" data-id=\"77d46de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0646\u0642\u0634\u0647\u200c\u0647\u0627 \u0648 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0647\u0648\u0627\u06cc\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0639\u0648\u0627\u0645\u0644 \u0648 \u067e\u0627\u0631\u0627\u0645\u062a\u0631\u0647\u0627\u06cc \u0627\u0633\u0627\u0633\u06cc \u062f\u0631 \u0645\u0631\u0627\u062d\u0644 \u0645\u062e\u062a\u0644\u0641 <strong>\u0637\u0631\u0627\u062d\u06cc \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong> \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p><p>\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0648\u0633\u0639\u062a \u067e\u0631\u0648\u0698\u0647 \u06a9\u0648\u0686\u06a9 \u0628\u0627\u0634\u062f\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0627\u062d\u062f\u0627\u062b \u0634\u0628\u06a9\u0647 \u0641\u0631\u0639\u06cc\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645 \u0632\u0647\u06a9\u0634\u06cc \u0632\u06cc\u0631\u0632\u0645\u06cc\u0646\u06cc \u06cc\u0627 \u062a\u0633\u0637\u06cc\u062d \u0627\u0631\u0627\u0636\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c<\/p><p>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0646\u0642\u0634\u0647\u200c\u0647\u0627\u06cc \u062a\u0648\u067e\u0648\u06af\u0631\u0627\u0641\u06cc \u0628\u0627 \u062e\u0637\u0648\u0637 \u062a\u0631\u0627\u0632 \u0645\u0634\u062e\u0635 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u06cc\u0632\u0627\u0646 \u0634\u06cc\u0628 \u0632\u0645\u06cc\u0646 \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646 \u0646\u0642\u0634\u0647\u200c\u0628\u0631\u062f\u0627\u0631\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0646\u0642\u0634\u0647 \u0645\u0628\u0646\u0627 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a. \u062a\u0635\u0627\u0648\u06cc\u0631 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u0645\u0631\u0627\u062d\u0644 \u0645\u062e\u062a\u0644\u0641 \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0627\u062c\u0631\u0627\u06cc \u0633\u06cc\u0633\u062a\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0628\u0647 \u0634\u0631\u062d \u0632\u06cc\u0631 \u0627\u0633\u062a.<\/p><ul><li><span style=\"color: #ff0000;\">\u0645\u0631\u062d\u0644\u0647 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc: \u062a\u0635\u0627\u0648\u06cc\u0631 \u0647\u0648\u0627\u06cc\u06cc \u0628\u0627 \u0645\u0642\u06cc\u0627\u0633 1:20000 \u06cc\u0627 \u062d\u062f\u0627\u0642\u0644 1:50000 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f.<\/span><\/li><li><span style=\"color: #ff0000;\">\u0645\u0631\u062d\u0644\u0647 \u062a\u0648\u062c\u06cc\u0647\u06cc: \u062a\u0635\u0627\u0648\u06cc\u0631 \u0647\u0648\u0627\u06cc\u06cc \u0628\u0627 \u0645\u0642\u06cc\u0627\u0633 1:20000 \u06cc\u0627 1:10000 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0645\u0646\u0637\u0642\u0647 \u0637\u0631\u062d \u06a9\u0648\u0686\u06a9\u200c\u062a\u0631 \u0627\u0632 2000 \u0647\u06a9\u062a\u0627\u0631 \u0628\u0627\u0634\u062f\u060c \u0627\u0632 \u062a\u0635\u0627\u0648\u06cc\u0631 1:10000 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li><li><span style=\"color: #ff0000;\">\u0645\u0631\u062d\u0644\u0647 \u062a\u0641\u0635\u06cc\u0644\u06cc: \u062a\u0635\u0627\u0648\u06cc\u0631 \u0647\u0648\u0627\u06cc\u06cc \u0628\u0627 \u0645\u0642\u06cc\u0627\u0633 1:5000 \u06cc\u0627 1:6500 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a \u0639\u062f\u0645 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u062a\u0635\u0627\u0648\u06cc\u0631\u060c \u0627\u0632 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0628\u0627 \u0645\u0642\u06cc\u0627\u0633 1:10000 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21c817c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21c817c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3139e7b\" data-id=\"3139e7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd4a6f4 elementor-widget elementor-widget-heading\" data-id=\"fd4a6f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0645\u062d\u0627\u0633\u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u0622\u0628 \u0644\u0627\u0632\u0645 \u0648 \u0638\u0631\u0641\u06cc\u062a \u0634\u0628\u06a9\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76e477b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76e477b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0418b91\" data-id=\"0418b91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-201847d elementor-widget elementor-widget-text-editor\" data-id=\"201847d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0628\u0631\u0627\u06cc <strong>\u0631\u0627\u0647 \u0627\u0646\u062f\u0627\u0632\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong>\u060c \u0628\u0627\u06cc\u062f \u062f\u0648 \u0686\u06cc\u0632 \u0645\u0647\u0645 \u0631\u0627 \u0645\u062d\u0627\u0633\u0628\u0647 \u06a9\u0646\u06cc\u062f: \u0627\u0648\u0644\u060c \u0645\u0642\u062f\u0627\u0631 \u0622\u0628\u06cc \u06a9\u0647 \u0632\u0645\u06cc\u0646 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0634\u0645\u0627 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u062f\u060c \u0648 \u062f\u0648\u0645\u060c \u0638\u0631\u0641\u06cc\u062a \u0634\u0628\u06a9\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc (\u0644\u0648\u0644\u0647 \u0647\u0627 \u0648 \u06a9\u0627\u0646\u0627\u0644 \u0647\u0627).<\/p><p>\u0628\u0631\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0646\u06cc\u0627\u0632 \u0622\u0628\u06cc\u060c \u0628\u0627\u06cc\u062f \u0639\u0648\u0627\u0645\u0644\u06cc \u0645\u062b\u0644 \u0645\u0642\u062f\u0627\u0631 \u0622\u0628\u06cc \u06a9\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f\u060c \u0645\u06cc\u0632\u0627\u0646 \u0628\u0627\u0631\u0646\u062f\u06af\u06cc\u060c \u0648 \u0638\u0631\u0641\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u0646\u062a\u0642\u0627\u0644 \u0622\u0628 \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u0628\u0631\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0638\u0631\u0641\u06cc\u062a \u0634\u0628\u06a9\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc\u060c \u0628\u0627\u06cc\u062f \u0645\u0633\u0627\u062d\u062a \u0632\u0645\u06cc\u0646 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0647\u0631 \u06a9\u0627\u0646\u0627\u0644 \u067e\u0648\u0634\u0634 \u0645\u06cc \u062f\u0647\u062f \u0631\u0627 \u062f\u0631 &#8220;\u0647\u06cc\u062f\u0631\u0648\u0645\u062f\u0648\u0644&#8221; \u0636\u0631\u0628 \u06a9\u0646\u06cc\u062f.<\/p><p>\u0647\u06cc\u062f\u0631\u0648\u0645\u062f\u0648\u0644 \u06cc\u0639\u0646\u06cc \u0645\u0642\u062f\u0627\u0631 \u0622\u0628 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u062f\u0631 \u0648\u0627\u062d\u062f \u0632\u0645\u0627\u0646 \u0648 \u062f\u0631 \u0648\u0627\u062d\u062f \u0633\u0637\u062d. \u0647\u0631 \u0686\u0647 \u0645\u0633\u0627\u062d\u062a \u0632\u0645\u06cc\u0646 \u06a9\u0645\u062a\u0631 \u0628\u0627\u0634\u062f\u060c \u0647\u06cc\u062f\u0631\u0648\u0645\u062f\u0648\u0644 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u062a\u0639\u06cc\u06cc\u0646 \u0638\u0631\u0641\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u0646\u062a\u0642\u0627\u0644 \u0622\u0628\u060c \u0627\u0632 \u0647\u06cc\u062f\u0631\u0648\u0645\u062f\u0648\u0644 \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u06a9\u0634\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-968dafa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"968dafa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8cccf07\" data-id=\"8cccf07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-017925f elementor-widget elementor-widget-heading\" data-id=\"017925f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0633\u06cc\u0633\u062a\u0645\u200c \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15f2293 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15f2293\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a28e01\" data-id=\"1a28e01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-059e4c5 elementor-widget elementor-widget-text-editor\" data-id=\"059e4c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u062f\u0631 \u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u06af\u0630\u0634\u062a\u0647\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u0648 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u0628\u0648\u062f\u060c \u06a9\u0634\u0627\u0648\u0631\u0632\u0627\u0646 \u0648 \u0628\u0627\u063a\u062f\u0627\u0631\u0627\u0646 \u0645\u062c\u0628\u0648\u0631 \u0628\u0648\u062f\u0646\u062f \u0627\u0632 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645\u06cc \u0648 \u0641\u0644\u0632\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0648 \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f.<\/p><p>\u0627\u06cc\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u060c \u0645\u062a\u0623\u0633\u0641\u0627\u0646\u0647\u060c \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u062a\u0639\u062f\u062f\u06cc \u0647\u0645\u0631\u0627\u0647 \u0628\u0648\u062f\u0646\u062f \u06a9\u0647 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0648\u0632\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u060c \u0627\u062d\u062a\u0645\u0627\u0644 \u0628\u0627\u0644\u0627\u06cc \u0632\u0646\u06af\u200c\u0632\u062f\u06af\u06cc \u0648 \u062e\u0648\u0631\u062f\u06af\u06cc\u060c \u0637\u0648\u0644 \u0639\u0645\u0631 \u0646\u0633\u0628\u062a\u0627\u064b \u06a9\u0648\u062a\u0627\u0647 \u0648 \u0645\u062d\u062f\u0648\u062f\u060c \u0648 \u062f\u0634\u0648\u0627\u0631\u06cc \u062f\u0631 \u0646\u0635\u0628 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.<\/p><p>\u0627\u0645\u0627 \u0627\u0645\u0631\u0648\u0632\u0647\u060c \u0628\u0627 \u067e\u06cc\u0634\u0631\u0641\u062a\u200c\u0647\u0627\u06cc \u0686\u0634\u0645\u06af\u06cc\u0631 \u062f\u0631 \u0635\u0646\u0639\u062a \u062a\u0648\u0644\u06cc\u062f \u0644\u0648\u0644\u0647\u060c \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u067e\u0644\u06cc\u200c\u0627\u062a\u06cc\u0644\u0646\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627 \u0645\u0639\u0631\u0641\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f.<\/p><p>\u0627\u06cc\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u062f\u0627\u0634\u062a\u0646 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0641\u0644\u0632\u06cc\u060c \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0641\u0634\u0627\u0631\u060c \u0636\u0631\u0628\u0647 \u0648 \u062e\u0648\u0631\u062f\u06af\u06cc \u0646\u06cc\u0632 \u0645\u0642\u0627\u0648\u0645\u062a \u0641\u0648\u0642\u200c\u0627\u0644\u0639\u0627\u062f\u0647\u200c\u0627\u06cc \u0627\u0632 \u062e\u0648\u062f \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u062e\u0631\u06cc\u062f \u0648 \u0646\u0635\u0628 \u0622\u0646\u200c\u0647\u0627 \u0646\u06cc\u0632 \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u06a9\u0645\u062a\u0631 \u0627\u0632 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0641\u0644\u0632\u06cc \u0627\u0633\u062a.<\/p><p>\u0627\u06cc\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u067e\u0644\u06cc\u200c\u0627\u062a\u06cc\u0644\u0646\u06cc \u062f\u0631 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u0647\u0627 \u0648 \u0642\u0637\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644\u060c \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u0627\u0646\u0648\u0627\u0639 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u06af\u0648\u0646\u0627\u06af\u0648\u0646 \u0648 \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 \u0645\u062a\u0641\u0627\u0648\u062a \u06a9\u0627\u0645\u0644\u0627\u064b \u0645\u0646\u0627\u0633\u0628 \u0647\u0633\u062a\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96e7ac7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96e7ac7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4f80f7\" data-id=\"b4f80f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11fc88b elementor-widget elementor-widget-heading\" data-id=\"11fc88b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0646\u062a\u06cc\u062c\u0647 \u06af\u06cc\u0631\u06cc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd95841 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd95841\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15c1a75\" data-id=\"15c1a75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9f7080 elementor-widget elementor-widget-text-editor\" data-id=\"e9f7080\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/strong>\u060c \u06a9\u0647 \u0631\u0648\u0634\u06cc \u0645\u062f\u0631\u0646 \u0648 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u062f\u0631 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0631\u0648\u062f\u060c<\/p><p>\u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0631\u0648\u0634 \u0633\u0646\u062a\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u0633\u0637\u062d\u06cc\u060c \u0641\u0648\u0627\u06cc\u062f \u0648 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u0628\u0633\u06cc\u0627\u0631 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u062f\u061b \u0627\u06cc\u0646 \u0634\u06cc\u0648\u0647 \u0646\u0648\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u06a9\u0627\u0647\u0634 \u0686\u0634\u0645\u06af\u06cc\u0631 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0622\u0628 \u0648 \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631\u060c \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647 \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628\u060c \u0648 \u0628\u0647\u0628\u0648\u062f \u0642\u0627\u0628\u0644 \u0645\u0644\u0627\u062d\u0638\u0647 \u062f\u0631 \u0628\u0627\u0632\u062f\u0647\u06cc \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u062a\u0627\u062b\u06cc\u0631 \u0645\u062b\u0628\u062a\u06cc \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p><p><span style=\"color: #008000;\">\u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0628\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0634\u06a9\u0644 \u0645\u0645\u06a9\u0646 \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f \u0648 \u0646\u062a\u0627\u06cc\u062c \u0645\u0637\u0644\u0648\u0628 \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0639\u0648\u0627\u0645\u0644 \u0648 \u0645\u062a\u063a\u06cc\u0631\u0647\u0627\u06cc \u06af\u0648\u0646\u0627\u06af\u0648\u0646\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0648\u0636\u0639\u06cc\u062a \u067e\u0633\u062a\u06cc \u0648 \u0628\u0644\u0646\u062f\u06cc \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u0634\u0631\u0627\u06cc\u0637 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u062a\u0623\u0645\u06cc\u0646 \u0627\u0646\u0631\u0698\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0628\u0631\u0627\u06cc \u067e\u0645\u067e\u200c\u0647\u0627 \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a\u060c \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u0648 \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0648 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062e\u0627\u06a9\u060c \u0645\u0642\u062f\u0627\u0631 \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0622\u0628 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc\u060c \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0646\u062d\u0648\u0647 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627 \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u0648\u062c\u0647 \u0648\u06cc\u0698\u0647 \u0634\u0648\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0628\u0627 \u0627\u0646\u0648\u0627\u0639 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632 \u0648 \u0627\u062c\u0631\u0627\u06cc \u0622\u0646 \u0635\u062d\u0628\u062a \u0645\u06cc \u06a9\u0646\u06cc\u0645!<\/p>\n","protected":false},"author":5,"featured_media":2145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-18"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0622\u0645\u0648\u0632\u0634 \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 + \u0641\u0631\u0645\u0648\u0644 \u0645\u062d\u0627\u0633\u0628\u0647 \u0641\u0634\u0627\u0631 \u06a9\u0627\u0631\u06cc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abloolearasepahan.com\/\u0622\u0628\u06cc\u0627\u0631\u06cc-\u062a\u062d\u062a-\u0641\u0634\u0627\u0631\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u0645\u0639\u0631\u0641\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0646!\" \/>\n<meta property=\"og:description\" content=\"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0628\u0627 \u0627\u0646\u0648\u0627\u0639 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632 \u0648 \u0627\u062c\u0631\u0627\u06cc \u0622\u0646 \u0635\u062d\u0628\u062a \u0645\u06cc \u06a9\u0646\u06cc\u0645!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abloolearasepahan.com\/\u0622\u0628\u06cc\u0627\u0631\u06cc-\u062a\u062d\u062a-\u0641\u0634\u0627\u0631\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0634\u0631\u06a9\u062a \u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-25T10:18:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T06:12:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abloolehara\" \/>\n<meta name=\"twitter:site\" content=\"@abloolehara\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/\"},\"author\":{\"name\":\"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a\",\"@id\":\"https:\/\/abloolearasepahan.com\/#\/schema\/person\/ea83b86e709d37d19ec5e07d37b65915\"},\"headline\":\"\u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u0645\u0639\u0631\u0641\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0646!\",\"datePublished\":\"2025-03-25T10:18:17+00:00\",\"dateModified\":\"2025-06-02T06:12:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/\"},\"wordCount\":0,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/abloolearasepahan.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp\",\"articleSection\":[\"\u0645\u0637\u0627\u0644\u0628\"],\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/\",\"url\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/\",\"name\":\"\u0622\u0645\u0648\u0632\u0634 \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 + \u0641\u0631\u0645\u0648\u0644 \u0645\u062d\u0627\u0633\u0628\u0647 \u0641\u0634\u0627\u0631 \u06a9\u0627\u0631\u06cc\",\"isPartOf\":{\"@id\":\"https:\/\/abloolearasepahan.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp\",\"datePublished\":\"2025-03-25T10:18:17+00:00\",\"dateModified\":\"2025-06-02T06:12:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage\",\"url\":\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp\",\"contentUrl\":\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp\",\"width\":1000,\"height\":500,\"caption\":\"\u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/abloolearasepahan.com\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u0645\u0639\u0631\u0641\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0646!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abloolearasepahan.com\/#website\",\"url\":\"https:\/\/abloolearasepahan.com\/\",\"name\":\"\u0634\u0631\u06a9\u062a \u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646\",\"description\":\"\u062a\u0648\u0644\u06cc\u062f \u0644\u0648\u0644\u0647 \u067e\u0644\u06cc \u0627\u062a\u06cc\u0644\u0646 \u062f\u0631 \u0627\u0635\u0641\u0647\u0627\u0646\",\"publisher\":{\"@id\":\"https:\/\/abloolearasepahan.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abloolearasepahan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/abloolearasepahan.com\/#organization\",\"name\":\"\u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646\",\"url\":\"https:\/\/abloolearasepahan.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/abloolearasepahan.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2022\/02\/logo1.png\",\"contentUrl\":\"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2022\/02\/logo1.png\",\"width\":251,\"height\":125,\"caption\":\"\u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646\"},\"image\":{\"@id\":\"https:\/\/abloolearasepahan.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/abloolehara\",\"https:\/\/www.instagram.com\/ablooleara.official\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/abloolearasepahan.com\/#\/schema\/person\/ea83b86e709d37d19ec5e07d37b65915\",\"name\":\"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/abloolearasepahan.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62663898958300ee8dc86979875891b95e4eb1ed599d4ac3c61373b77df82888?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62663898958300ee8dc86979875891b95e4eb1ed599d4ac3c61373b77df82888?s=96&d=mm&r=g\",\"caption\":\"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a\"},\"url\":\"https:\/\/abloolearasepahan.com\/ar\/author\/site_admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0622\u0645\u0648\u0632\u0634 \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 + \u0641\u0631\u0645\u0648\u0644 \u0645\u062d\u0627\u0633\u0628\u0647 \u0641\u0634\u0627\u0631 \u06a9\u0627\u0631\u06cc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abloolearasepahan.com\/\u0622\u0628\u06cc\u0627\u0631\u06cc-\u062a\u062d\u062a-\u0641\u0634\u0627\u0631\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u0645\u0639\u0631\u0641\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0646!","og_description":"\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0628\u0627 \u0627\u0646\u0648\u0627\u0639 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632 \u0648 \u0627\u062c\u0631\u0627\u06cc \u0622\u0646 \u0635\u062d\u0628\u062a \u0645\u06cc \u06a9\u0646\u06cc\u0645!","og_url":"https:\/\/abloolearasepahan.com\/\u0622\u0628\u06cc\u0627\u0631\u06cc-\u062a\u062d\u062a-\u0641\u0634\u0627\u0631\/","og_site_name":"\u0634\u0631\u06a9\u062a \u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646","article_published_time":"2025-03-25T10:18:17+00:00","article_modified_time":"2025-06-02T06:12:24+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp","type":"image\/webp"}],"author":"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a","twitter_card":"summary_large_image","twitter_creator":"@abloolehara","twitter_site":"@abloolehara","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"11 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#article","isPartOf":{"@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/"},"author":{"name":"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a","@id":"https:\/\/abloolearasepahan.com\/#\/schema\/person\/ea83b86e709d37d19ec5e07d37b65915"},"headline":"\u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u0645\u0639\u0631\u0641\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0646!","datePublished":"2025-03-25T10:18:17+00:00","dateModified":"2025-06-02T06:12:24+00:00","mainEntityOfPage":{"@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/"},"wordCount":0,"commentCount":1,"publisher":{"@id":"https:\/\/abloolearasepahan.com\/#organization"},"image":{"@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp","articleSection":["\u0645\u0637\u0627\u0644\u0628"],"inLanguage":"ar","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/","url":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/","name":"\u0622\u0645\u0648\u0632\u0634 \u0627\u062c\u0631\u0627\u06cc \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 + \u0641\u0631\u0645\u0648\u0644 \u0645\u062d\u0627\u0633\u0628\u0647 \u0641\u0634\u0627\u0631 \u06a9\u0627\u0631\u06cc","isPartOf":{"@id":"https:\/\/abloolearasepahan.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage"},"image":{"@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp","datePublished":"2025-03-25T10:18:17+00:00","dateModified":"2025-06-02T06:12:24+00:00","breadcrumb":{"@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#primaryimage","url":"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp","contentUrl":"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2025\/03\/Irrigation-under-pressure-index-webp.webp","width":1000,"height":500,"caption":"\u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631"},{"@type":"BreadcrumbList","@id":"https:\/\/abloolearasepahan.com\/%d8%a2%d8%a8%db%8c%d8%a7%d8%b1%db%8c-%d8%aa%d8%ad%d8%aa-%d9%81%d8%b4%d8%a7%d8%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abloolearasepahan.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0648 \u0645\u0639\u0631\u0641\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0622\u0646!"}]},{"@type":"WebSite","@id":"https:\/\/abloolearasepahan.com\/#website","url":"https:\/\/abloolearasepahan.com\/","name":"\u0634\u0631\u06a9\u062a \u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646","description":"\u062a\u0648\u0644\u06cc\u062f \u0644\u0648\u0644\u0647 \u067e\u0644\u06cc \u0627\u062a\u06cc\u0644\u0646 \u062f\u0631 \u0627\u0635\u0641\u0647\u0627\u0646","publisher":{"@id":"https:\/\/abloolearasepahan.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abloolearasepahan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/abloolearasepahan.com\/#organization","name":"\u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646","url":"https:\/\/abloolearasepahan.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/abloolearasepahan.com\/#\/schema\/logo\/image\/","url":"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2022\/02\/logo1.png","contentUrl":"https:\/\/abloolearasepahan.com\/wp-content\/uploads\/2022\/02\/logo1.png","width":251,"height":125,"caption":"\u0622\u0628 \u0644\u0648\u0644\u0647 \u0622\u0631\u0627 \u0633\u067e\u0627\u0647\u0627\u0646"},"image":{"@id":"https:\/\/abloolearasepahan.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/abloolehara","https:\/\/www.instagram.com\/ablooleara.official\/"]},{"@type":"Person","@id":"https:\/\/abloolearasepahan.com\/#\/schema\/person\/ea83b86e709d37d19ec5e07d37b65915","name":"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/abloolearasepahan.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62663898958300ee8dc86979875891b95e4eb1ed599d4ac3c61373b77df82888?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62663898958300ee8dc86979875891b95e4eb1ed599d4ac3c61373b77df82888?s=96&d=mm&r=g","caption":"\u0645\u062f\u06cc\u0631 \u0633\u0627\u06cc\u062a"},"url":"https:\/\/abloolearasepahan.com\/ar\/author\/site_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/posts\/2138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/comments?post=2138"}],"version-history":[{"count":13,"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/posts\/2138\/revisions"}],"predecessor-version":[{"id":2258,"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/posts\/2138\/revisions\/2258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/media\/2145"}],"wp:attachment":[{"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/media?parent=2138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/categories?post=2138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abloolearasepahan.com\/ar\/wp-json\/wp\/v2\/tags?post=2138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}